{"id":424,"count":2,"description":"","link":"https:\/\/www.tanalahorizon.com\/en\/tag\/reisesicherungsschein\/","name":"travel security note","slug":"reisesicherungsschein","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>travel security note Archive - Tanalahorizon - Madagaskar travels since 1995<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tanalahorizon.com\/en\/tag\/reisesicherungsschein\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"travel security note Archive - Tanalahorizon - Madagaskar travels since 1995\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tanalahorizon.com\/en\/tag\/reisesicherungsschein\/\" \/>\n<meta property=\"og:site_name\" content=\"Tanalahorizon - Madagaskar travels since 1995\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tanalahorizon.com\/wp-content\/uploads\/2015\/08\/Baobabs-schmal-e1444557371963.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@tanalahorizon\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.tanalahorizon.com\/en\/tag\/reisesicherungsschein\/\",\"url\":\"https:\/\/www.tanalahorizon.com\/en\/tag\/reisesicherungsschein\/\",\"name\":\"travel security note Archive - Tanalahorizon - Madagaskar travels since 1995\",\"isPartOf\":{\"@id\":\"https:\/\/www.tanalahorizon.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.tanalahorizon.com\/en\/tag\/reisesicherungsschein\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tanalahorizon.com\/en\/tag\/reisesicherungsschein\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tanalahorizon.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reisesicherungsschein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tanalahorizon.com\/en\/#website\",\"url\":\"https:\/\/www.tanalahorizon.com\/en\/\",\"name\":\"Tanalahorizon - Madagaskar travels since 1995\",\"description\":\"Your travel agency for Madagascar\",\"publisher\":{\"@id\":\"https:\/\/www.tanalahorizon.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tanalahorizon.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tanalahorizon.com\/de\/#organization\",\"name\":\"TANALAHORIZON - Madagaskar-Reisen seit 1995\",\"url\":\"https:\/\/www.tanalahorizon.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.tanalahorizon.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tanalahorizon.com\/wp-content\/uploads\/2015\/09\/logo2_300px.png\",\"contentUrl\":\"https:\/\/www.tanalahorizon.com\/wp-content\/uploads\/2015\/09\/logo2_300px.png\",\"width\":300,\"height\":149,\"caption\":\"TANALAHORIZON - Madagaskar-Reisen seit 1995\"},\"image\":{\"@id\":\"https:\/\/www.tanalahorizon.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/TANALAHORIZON\",\"https:\/\/x.com\/tanalahorizon\",\"https:\/\/www.youtube.com\/user\/TANALAHORIZON\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"travel security note Archive - Tanalahorizon - Madagaskar travels since 1995","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tanalahorizon.com\/en\/tag\/reisesicherungsschein\/","og_locale":"en_US","og_type":"article","og_title":"travel security note Archive - Tanalahorizon - Madagaskar travels since 1995","og_url":"https:\/\/www.tanalahorizon.com\/en\/tag\/reisesicherungsschein\/","og_site_name":"Tanalahorizon - Madagaskar travels since 1995","og_image":[{"width":1500,"height":638,"url":"https:\/\/www.tanalahorizon.com\/wp-content\/uploads\/2015\/08\/Baobabs-schmal-e1444557371963.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@tanalahorizon","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.tanalahorizon.com\/en\/tag\/reisesicherungsschein\/","url":"https:\/\/www.tanalahorizon.com\/en\/tag\/reisesicherungsschein\/","name":"travel security note Archive - Tanalahorizon - Madagaskar travels since 1995","isPartOf":{"@id":"https:\/\/www.tanalahorizon.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.tanalahorizon.com\/en\/tag\/reisesicherungsschein\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tanalahorizon.com\/en\/tag\/reisesicherungsschein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tanalahorizon.com\/en\/"},{"@type":"ListItem","position":2,"name":"Reisesicherungsschein"}]},{"@type":"WebSite","@id":"https:\/\/www.tanalahorizon.com\/en\/#website","url":"https:\/\/www.tanalahorizon.com\/en\/","name":"Tanalahorizon - Madagaskar travels since 1995","description":"Your travel agency for Madagascar","publisher":{"@id":"https:\/\/www.tanalahorizon.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tanalahorizon.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.tanalahorizon.com\/de\/#organization","name":"TANALAHORIZON - Madagaskar-Reisen seit 1995","url":"https:\/\/www.tanalahorizon.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tanalahorizon.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.tanalahorizon.com\/wp-content\/uploads\/2015\/09\/logo2_300px.png","contentUrl":"https:\/\/www.tanalahorizon.com\/wp-content\/uploads\/2015\/09\/logo2_300px.png","width":300,"height":149,"caption":"TANALAHORIZON - Madagaskar-Reisen seit 1995"},"image":{"@id":"https:\/\/www.tanalahorizon.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TANALAHORIZON","https:\/\/x.com\/tanalahorizon","https:\/\/www.youtube.com\/user\/TANALAHORIZON"]}]}},"_links":{"self":[{"href":"https:\/\/www.tanalahorizon.com\/en\/wp-json\/wp\/v2\/tags\/424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tanalahorizon.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.tanalahorizon.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.tanalahorizon.com\/en\/wp-json\/wp\/v2\/posts?tags=424"},{"href":"https:\/\/www.tanalahorizon.com\/en\/wp-json\/wp\/v2\/pages?tags=424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}